{"id":159,"date":"2019-04-27T11:44:48","date_gmt":"2019-04-27T09:44:48","guid":{"rendered":"https:\/\/projekte.uni-erfurt.de\/efosi\/?page_id=159"},"modified":"2019-04-27T11:46:17","modified_gmt":"2019-04-27T09:46:17","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/projekte.uni-erfurt.de\/efosi\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"\n<p>Du hast Fragen oder Hinweise? <\/p>\n\n\n\n<p>Oder du m\u00f6chtest Mitglied bei EFOSI werden?<\/p>\n\n\n\n<p>Wir freuen uns auf deinen E-Mail: efosi@uni-erfurt.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du hast Fragen oder Hinweise? Oder du m\u00f6chtest Mitglied bei EFOSI werden? Wir freuen uns auf deinen E-Mail: efosi@uni-erfurt.de<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/pages\/159"}],"collection":[{"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/comments?post=159"}],"version-history":[{"count":2,"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/pages\/159\/revisions"}],"predecessor-version":[{"id":163,"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/pages\/159\/revisions\/163"}],"wp:attachment":[{"href":"https:\/\/projekte.uni-erfurt.de\/efosi\/wp-json\/wp\/v2\/media?parent=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}